{"id":6825,"date":"2021-04-14T11:18:07","date_gmt":"2021-04-14T09:18:07","guid":{"rendered":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/?p=6825"},"modified":"2021-04-14T11:18:07","modified_gmt":"2021-04-14T09:18:07","slug":"retour-sur-denain-voltaire-antibes","status":"publish","type":"post","link":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/retour-sur-denain-voltaire-antibes\/","title":{"rendered":"RETOUR SUR : DENAIN VOLTAIRE \/ ANTIBES"},"content":{"rendered":"<p><b>Se reprendre \u00e0 domicile<\/b><\/p>\n<p>Apr\u00e8s la d\u00e9route face \u00e0 Lille, les Dragons recevaient les Sharks d\u2019Antibes pour un retour sur le parquet de Degros apr\u00e8s deux d\u00e9placements. L\u2019occasion de se reprendre \u00e0 domicile, face \u00e0 une \u00e9quipe d\u2019Antibes en difficult\u00e9 dans ce championnat de ProB. En effet, en cas de d\u00e9faite, les Sharks descendraient \u00e0 la 17<sup>e<\/sup> place synonyme de descente en NM1. De plus les azur\u00e9ens ont \u00e9galement re\u00e7u une claque vendredi face \u00e0 Blois inscrivant seulement 7 points dans le premier quart temps. Les deux \u00e9quipes avaient donc \u00e0 c\u0153ur de laver l\u2019affront.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-6826\" src=\"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4.jpg\" alt=\"\" width=\"1100\" height=\"365\" srcset=\"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-200x66.jpg 200w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-300x100.jpg 300w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-400x133.jpg 400w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-600x199.jpg 600w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-768x255.jpg 768w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-800x265.jpg 800w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4-1024x340.jpg 1024w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/slide-resultats-4.jpg 1100w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p><b>Un ma\u00eetris\u00e9 dans l\u2019ensemble<\/b><\/p>\n<p>Dans ce match, ce sont les Dragons qui ont su imposer leur rythme. D\u00e8s le d\u00e9but de match Voltaire s\u2019est impos\u00e9 dans la maitrise, gardant son sang-froid, m\u00eame quand Antibes semblait vouloir passer \u00e0 la vitesse sup\u00e9rieure avec un \u00e9cart de 6 points \u00e0 la pause en faveur des bleus. Effectivement, Denain aurait pu se faire peur mais cela aurait \u00e9t\u00e9 sans compter sur les hommes en forme de R\u00e9my Valin. Une nouvelle fois, Chris-Ebou Ndow \u00e9lu MVP de la rencontre, fini \u00e0 16 points avec 60% \u00e0 3 points\u00a0; David Skara confirme la r\u00e9gularit\u00e9 que tout le monde lui connait, et Stephen Brown, encore une fois, prend le match \u00e0 son compte pour aller chercher les clutchs et la victoire. \u00c0 cela ajoutons les performances de Quentin Losser et de Rigo Edzata \u00e0 80% au shoot, ce qui permet \u00e0 Denain de compter 5 joueurs \u00e0 plus de 10 d\u2019\u00e9valuation\u00a0! Le point noir de la soir\u00e9e, sera \u00e9videmment la blessure de Ruphin Kayembe, bless\u00e9 au genou en retombant, la p\u00e9riode d\u2019indisponibilit\u00e9 de l\u2019international Congolais n\u2019est pas encore connue. Nous lui souhaitons un bon r\u00e9tablissement en esp\u00e9rant le revoir rapidement sur les parquets avec le maillot de Voltaire.<\/p>\n<p><b>La confirmation face \u00e0 Saint-Chamond<\/b><\/p>\n<p>Apr\u00e8s cette belle victoire, les Denaisiens auront d\u00e9j\u00e0 l\u2019occasion de confirmer vendredi soir face \u00e0 Saint-Chamond. Une \u00e9quipe qui n\u2019a pas gagn\u00e9 depuis d\u00e9cembre, mais qui compte dans ses rangs un ancien de la maison, J\u00e9r\u00f4me Cazenobe\u00a0!<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-6829\" src=\"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360.jpeg\" alt=\"\" width=\"1180\" height=\"787\" srcset=\"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-200x133.jpeg 200w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-300x200.jpeg 300w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-400x267.jpeg 400w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-600x400.jpeg 600w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-768x512.jpeg 768w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-800x534.jpeg 800w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360-1024x683.jpeg 1024w, http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-content\/uploads\/2021\/04\/Resized_DSC_2007_13853900442360.jpeg 1180w\" sizes=\"(max-width: 1180px) 100vw, 1180px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se reprendre \u00e0 domicile Apr\u00e8s la d\u00e9route face \u00e0 Lille, les Dragons recevaient les Sharks d\u2019Antibes pour un retour sur le parquet de Degros apr\u00e8s deux d\u00e9placements. L\u2019occasion de se reprendre \u00e0 domicile, face \u00e0 une \u00e9quipe d\u2019Antibes en difficult\u00e9 dans ce championnat de ProB. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13,18],"tags":[],"_links":{"self":[{"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/posts\/6825"}],"collection":[{"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/comments?post=6825"}],"version-history":[{"count":2,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/posts\/6825\/revisions"}],"predecessor-version":[{"id":6830,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/posts\/6825\/revisions\/6830"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/media\/6827"}],"wp:attachment":[{"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/media?parent=6825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/categories?post=6825"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.denainvoltairehainaut-basket.fr\/wp2016\/wp-json\/wp\/v2\/tags?post=6825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}